{"id":37691,"date":"2023-02-22T11:39:38","date_gmt":"2023-02-22T10:39:38","guid":{"rendered":"https:\/\/www.gt-engineering.it\/?post_type=approfondimento&#038;p=37691"},"modified":"2023-08-01T11:57:49","modified_gmt":"2023-08-01T10:57:49","slug":"tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines","status":"publish","type":"approfondimento","link":"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/","title":{"rendered":"TABRA : Une approche bas\u00e9e sur les t\u00e2ches pour \u00e9valuer le risque dans la s\u00e9curit\u00e9 des machines"},"content":{"rendered":"\n\n    \n        <section\n            data-name=\"Contenuto testuale con immagine\"\n            class=\"bow-gte-testo-media u-spacer-base\"\n            id=\"\"\n        >\n            \n<div class=\"o-text-media px-side-spacer sm:px-side-spacer-sm lg:px-side-spacer-tablet 2xl:px-side-spacer-desktop flex flex-wrap items-start md:block\">\n\n    \n        \n                    <div\n                class=\"h-auto mb-6 md:mb-4 lg:mb-8 xl:mb-9 float-left mr-6 md:mr-4 lg:mr-8 xl:mr-9  overflow-hidden shadow-content-image w-full md:w-1\/3\"\n            >\n                \r\n\r\n    \r\n        \r\n            \r\n                \r\n                    <picture\r\n                        class=\"\"\r\n                                            >\r\n                                                                                                        <source\r\n                                media=\"(max-width: 150px)\"\r\n                                width=\"150\"\r\n                                height=\"150\"\r\n                                srcset=\"https:\/\/www.gt-engineering.it\/wp-content\/uploads\/2023\/02\/Terminology-used-in-B11-standards-768x576-1-150x150.webp\"\r\n                                type=\"image\/webp\"\r\n                            \/>\r\n                                                                                <source\r\n                                media=\"(max-width: 300px)\"\r\n                                width=\"300\"\r\n                                height=\"225\"\r\n                                srcset=\"https:\/\/www.gt-engineering.it\/wp-content\/uploads\/2023\/02\/Terminology-used-in-B11-standards-768x576-1-300x225.webp\"\r\n                                type=\"image\/webp\"\r\n                            \/>\r\n                                                                                <source\r\n                                media=\"(max-width: 768px)\"\r\n                                width=\"768\"\r\n                                height=\"576\"\r\n                                srcset=\"https:\/\/www.gt-engineering.it\/wp-content\/uploads\/2023\/02\/Terminology-used-in-B11-standards-768x576-1.webp\"\r\n                                type=\"image\/webp\"\r\n                            \/>\r\n                                                                                <source\r\n                                media=\"(max-width: 768px)\"\r\n                                width=\"768\"\r\n                                height=\"576\"\r\n                                srcset=\"https:\/\/www.gt-engineering.it\/wp-content\/uploads\/2023\/02\/Terminology-used-in-B11-standards-768x576-1.webp\"\r\n                                type=\"image\/webp\"\r\n                            \/>\r\n                                                                            <img\r\n                            class=\"a-image transparent border-image h-auto  w-full\"\r\n                                                        srcset=\"https:\/\/www.gt-engineering.it\/wp-content\/uploads\/2023\/02\/Terminology-used-in-B11-standards-768x576-1.webp\"\r\n                                                        title=\"Terminology-used-in-B11-standards-768&#215;576-1\"\r\n                                                        type=\"image\/webp\"\r\n                        \/>\r\n                    <\/picture>\r\n\r\n                \r\n\r\n                    \r\n    \r\n            <\/div>\n        \n                    <div class=\"relative w-full\">\n                \n<div class=\"a-text font-text text-base normal mt-8 first:mt-0 space-y-4\">\n    <p>Lorsque nous appliquons la norme ISO 12100, nous avons tendance \u00e0 nous concentrer sur les dangers qui r\u00e9sultent de situations auxquelles un op\u00e9rateur ou l&rsquo;\u00e9quipe de maintenance peut \u00eatre confront\u00e9, alors qu&rsquo;en Am\u00e9rique du Nord, on a tendance \u00e0 se concentrer sur les dangers associ\u00e9s aux t\u00e2ches qu&rsquo;une personne peut \u00eatre amen\u00e9e \u00e0 effectuer. En substance, la majorit\u00e9 des proc\u00e9dures europ\u00e9ennes d&rsquo;\u00e9valuation des risques sont bas\u00e9es sur les dangers, tandis qu&rsquo;aux \u00c9tats-Unis et au Canada, elles sont bas\u00e9es sur les t\u00e2ches. C&rsquo;est la signification de l&rsquo;acronyme largement utilis\u00e9 aux \u00c9tats-Unis : TABRA. La norme de r\u00e9f\u00e9rence est<strong> ANSI RIA TR R15.306.<\/strong><\/p>\n<p>Le concept <strong>d&rsquo;\u00e9valuation des risques bas\u00e9e sur les t\u00e2ches<\/strong> est mentionn\u00e9 dans la nouvelle \u00e9dition de la norme EN ISO 11161, la norme de r\u00e9f\u00e9rence concernant la s\u00e9curit\u00e9 des syst\u00e8mes int\u00e9gr\u00e9s de machines (IMS) ; il est mentionn\u00e9 en m\u00eame temps que celui bas\u00e9 sur les dangers, ce qui signifie que les deux sont importants.<\/p>\n<p>L&rsquo;\u00e9valuation des risques bas\u00e9e sur les t\u00e2ches est un processus formel d&rsquo;identification des dangers associ\u00e9s \u00e0 chaque t\u00e2che \u00e0 effectuer, d&rsquo;\u00e9valuation des risques et de mise en place de contr\u00f4les de s\u00e9curit\u00e9 pour g\u00e9rer les risques. Les principales \u00e9tapes peuvent \u00eatre r\u00e9sum\u00e9es comme suit :<\/p>\n<ul>\n<li>Identifier les groupes qui interagissent avec une machine ;<\/li>\n<li>D\u00e9terminer les t\u00e2ches effectu\u00e9es sur la machine ;<\/li>\n<li>Identifier les dangers li\u00e9s \u00e0 l&rsquo;ex\u00e9cution de ces t\u00e2ches ;<\/li>\n<li>\u00c9valuer les risques \u00e0 l&rsquo;aide d&rsquo;un syst\u00e8me d&rsquo;\u00e9valuation des risques ;<\/li>\n<li>Si n\u00e9cessaire, r\u00e9duire le risque.<\/li>\n<\/ul>\n<p>Une fois le risque initial \u00e9valu\u00e9, il doit \u00eatre analys\u00e9.<br \/>\nSi le risque se situe \u00e0 un niveau tol\u00e9rable, il est possible d&rsquo;accepter le r\u00e9sultat ou d&rsquo;essayer de r\u00e9duire encore le risque, en fonction du co\u00fbt et de l&rsquo;effort d&rsquo;att\u00e9nuation.<\/p>\n<p>Si l&rsquo;analyse initiale des risques aboutit \u00e0 un niveau de risque inacceptable, l&rsquo;att\u00e9nuation des risques doit se faire de mani\u00e8re it\u00e9rative jusqu&rsquo;\u00e0 ce que le risque soit ramen\u00e9 \u00e0 un niveau tol\u00e9rable.<\/p>\n<ul>\n<li>Mesures de conception intrins\u00e8quement s\u00fbres<\/li>\n<li>Sauvegarde et \u00e9tendue des contr\u00f4les<\/li>\n<li>Informations pour l&rsquo;utilisation<\/li>\n<\/ul>\n<p><strong>Les t\u00e2ches normales et atypiques<\/strong> doivent \u00eatre r\u00e9pertori\u00e9es sur la base de l&rsquo;exp\u00e9rience du personnel et de l&rsquo;anticipation de ce qui pourrait se produire. Ce processus permet \u00e9galement de prendre en compte les diff\u00e9rentes cat\u00e9gories de parties prenantes qui interagissent avec la machine et d&rsquo;autres \u00e9l\u00e9ments qui peuvent affecter l&rsquo;environnement de travail (par exemple, le travail post\u00e9, les diff\u00e9rentes phases du cycle de production). La projection de sc\u00e9narios futurs est particuli\u00e8rement importante pour les machines qui ne sont pas encore utilis\u00e9es ou qui ont \u00e9t\u00e9 r\u00e9cemment mises en service.<\/p>\n<p>D&rsquo;apr\u00e8s notre exp\u00e9rience, <strong>une \u00e9valuation des risques bas\u00e9e sur les dangers tend \u00e0 produire une grande feuille Excel qui conduit \u00e0 minimiser les solutions \u00e0 utiliser pour r\u00e9duire les risques.<\/strong> Une \u00e9valuation des risques bas\u00e9e sur les t\u00e2ches utilise normalement des<strong> tableaux de risques<\/strong> o\u00f9 chaque tableau repr\u00e9sente un risque encouru par une personne et la mani\u00e8re de le r\u00e9duire. Les tableaux de risques sont g\u00e9n\u00e9ralement plus sp\u00e9cifiques et utilisables par l&rsquo;\u00e9quipe de d\u00e9veloppement ou d&rsquo;ing\u00e9nierie qui doit appliquer des mesures de protection \u00e0 la machine et par l&rsquo;op\u00e9rateur qui doit effectuer la t\u00e2che requise.<\/p>\n<p>L&rsquo;\u00e9valuation des risques machine bas\u00e9e sur les t\u00e2ches donne des r\u00e9sultats faciles \u00e0 quantifier et \u00e0 classer par ordre de priorit\u00e9 en fonction de leur score. Le syst\u00e8me de notation permet au personnel de l&rsquo;usine de se concentrer sur les t\u00e2ches pr\u00e9sentant les dangers les plus graves afin de r\u00e9duire concr\u00e8tement les risques.<\/p>\n<p>En conclusion, l&rsquo;\u00e9valuation des risques bas\u00e9e sur les t\u00e2ches est une autre fa\u00e7on d&rsquo;effectuer une \u00e9valuation des risques qui peut compl\u00e9ter celle bas\u00e9e sur les dangers, normalement utilis\u00e9e dans le domaine de la s\u00e9curit\u00e9 des machines. C&rsquo;est un bon moyen de g\u00e9rer les risques associ\u00e9s \u00e0 un travail critique qui doit \u00eatre effectu\u00e9 dans une zone critique. Il s&rsquo;agit d&rsquo;une approche syst\u00e9matique pour garantir la s\u00e9curit\u00e9 lors de l&rsquo;ex\u00e9cution de travaux critiques et contribuer ainsi \u00e0 la pr\u00e9vention des accidents. Il s&rsquo;agit d&rsquo;une activit\u00e9 d&rsquo;\u00e9quipe ; par cons\u00e9quent, pour que la TABRA soit efficace, il faut que des personnes de diff\u00e9rentes disciplines participent \u00e0 l&rsquo;identification des dangers, \u00e0 l&rsquo;\u00e9valuation des risques et \u00e0 la prise de d\u00e9cision concernant les mesures de contr\u00f4le.<\/p>\n<\/div>            <\/div>\n        \n        \n                <div class=\"clear-both\"><\/div>\n        \n\n    <\/div>\n        <\/section>\n\n    \n","protected":false},"excerpt":{"rendered":"<p>Lorsque nous appliquons la norme ISO 12100, nous avons tendance \u00e0 nous concentrer sur les dangers qui r\u00e9sultent de situations auxquelles un op\u00e9rateur ou l&rsquo;\u00e9quipe de maintenance peut \u00eatre confront\u00e9, alors qu&rsquo;en Am\u00e9rique du Nord, on a tendance \u00e0 se concentrer sur les dangers associ\u00e9s aux t\u00e2ches qu&rsquo;une personne peut \u00eatre amen\u00e9e \u00e0 effectuer.<\/p>\n","protected":false},"author":182,"featured_media":37692,"parent":0,"menu_order":43,"template":"","meta":{"_acf_changed":false,"footnotes":""},"tipologia_approfondimento":[152],"class_list":["post-37691","approfondimento","type-approfondimento","status-publish","has-post-thumbnail","hentry","tipologia_approfondimento-la-securite-des-machines"],"acf":{"sottotitolo":"","allegati":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TABRA : Une approche bas\u00e9e sur les t\u00e2ches pour \u00e9valuer le risque dans la s\u00e9curit\u00e9 des machines - Gt-Engineering<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TABRA : Une approche bas\u00e9e sur les t\u00e2ches pour \u00e9valuer le risque dans la s\u00e9curit\u00e9 des machines - Gt-Engineering\" \/>\n<meta property=\"og:description\" content=\"Lorsque nous appliquons la norme ISO 12100, nous avons tendance \u00e0 nous concentrer sur les dangers qui r\u00e9sultent de situations auxquelles un op\u00e9rateur ou l&#039;\u00e9quipe de maintenance peut \u00eatre confront\u00e9, alors qu&#039;en Am\u00e9rique du Nord, on a tendance \u00e0 se concentrer sur les dangers associ\u00e9s aux t\u00e2ches qu&#039;une personne peut \u00eatre amen\u00e9e \u00e0 effectuer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/\" \/>\n<meta property=\"og:site_name\" content=\"Gt-Engineering\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-01T10:57:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gt-engineering.it\/wp-content\/uploads\/2023\/07\/Cattura.png\" \/>\n\t<meta property=\"og:image:width\" content=\"513\" \/>\n\t<meta property=\"og:image:height\" content=\"342\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/\",\"url\":\"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/\",\"name\":\"TABRA : Une approche bas\u00e9e sur les t\u00e2ches pour \u00e9valuer le risque dans la s\u00e9curit\u00e9 des machines - Gt-Engineering\",\"isPartOf\":{\"@id\":\"https:\/\/www.gt-engineering.it\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.gt-engineering.it\/wp-content\/uploads\/2023\/07\/Cattura.png\",\"datePublished\":\"2023-02-22T10:39:38+00:00\",\"dateModified\":\"2023-08-01T10:57:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/#primaryimage\",\"url\":\"https:\/\/www.gt-engineering.it\/wp-content\/uploads\/2023\/07\/Cattura.png\",\"contentUrl\":\"https:\/\/www.gt-engineering.it\/wp-content\/uploads\/2023\/07\/Cattura.png\",\"width\":513,\"height\":342},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.gt-engineering.it\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c0 \u00e9tudier\",\"item\":\"https:\/\/www.gt-engineering.it\/fr\/approfondimenti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S\u00e9curit\u00e9 des Machines\",\"item\":\"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"TABRA : Une approche bas\u00e9e sur les t\u00e2ches pour \u00e9valuer le risque dans la s\u00e9curit\u00e9 des machines\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gt-engineering.it\/fr\/#website\",\"url\":\"https:\/\/www.gt-engineering.it\/fr\/\",\"name\":\"Gt-Engineering\",\"description\":\"bizonweb\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gt-engineering.it\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TABRA : Une approche bas\u00e9e sur les t\u00e2ches pour \u00e9valuer le risque dans la s\u00e9curit\u00e9 des machines - Gt-Engineering","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/","og_locale":"fr_FR","og_type":"article","og_title":"TABRA : Une approche bas\u00e9e sur les t\u00e2ches pour \u00e9valuer le risque dans la s\u00e9curit\u00e9 des machines - Gt-Engineering","og_description":"Lorsque nous appliquons la norme ISO 12100, nous avons tendance \u00e0 nous concentrer sur les dangers qui r\u00e9sultent de situations auxquelles un op\u00e9rateur ou l'\u00e9quipe de maintenance peut \u00eatre confront\u00e9, alors qu'en Am\u00e9rique du Nord, on a tendance \u00e0 se concentrer sur les dangers associ\u00e9s aux t\u00e2ches qu'une personne peut \u00eatre amen\u00e9e \u00e0 effectuer.","og_url":"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/","og_site_name":"Gt-Engineering","article_modified_time":"2023-08-01T10:57:49+00:00","og_image":[{"width":513,"height":342,"url":"https:\/\/www.gt-engineering.it\/wp-content\/uploads\/2023\/07\/Cattura.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/","url":"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/","name":"TABRA : Une approche bas\u00e9e sur les t\u00e2ches pour \u00e9valuer le risque dans la s\u00e9curit\u00e9 des machines - Gt-Engineering","isPartOf":{"@id":"https:\/\/www.gt-engineering.it\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/#primaryimage"},"image":{"@id":"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gt-engineering.it\/wp-content\/uploads\/2023\/07\/Cattura.png","datePublished":"2023-02-22T10:39:38+00:00","dateModified":"2023-08-01T10:57:49+00:00","breadcrumb":{"@id":"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/#primaryimage","url":"https:\/\/www.gt-engineering.it\/wp-content\/uploads\/2023\/07\/Cattura.png","contentUrl":"https:\/\/www.gt-engineering.it\/wp-content\/uploads\/2023\/07\/Cattura.png","width":513,"height":342},{"@type":"BreadcrumbList","@id":"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/tabra-une-approche-basee-sur-les-taches-pour-evaluer-le-risque-dans-la-securite-des-machines\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.gt-engineering.it\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c0 \u00e9tudier","item":"https:\/\/www.gt-engineering.it\/fr\/approfondimenti\/"},{"@type":"ListItem","position":3,"name":"S\u00e9curit\u00e9 des Machines","item":"https:\/\/www.gt-engineering.it\/fr\/approfondissement\/la-securite-des-machines\/"},{"@type":"ListItem","position":4,"name":"TABRA : Une approche bas\u00e9e sur les t\u00e2ches pour \u00e9valuer le risque dans la s\u00e9curit\u00e9 des machines"}]},{"@type":"WebSite","@id":"https:\/\/www.gt-engineering.it\/fr\/#website","url":"https:\/\/www.gt-engineering.it\/fr\/","name":"Gt-Engineering","description":"bizonweb","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gt-engineering.it\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.gt-engineering.it\/fr\/wp-json\/wp\/v2\/approfondimento\/37691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gt-engineering.it\/fr\/wp-json\/wp\/v2\/approfondimento"}],"about":[{"href":"https:\/\/www.gt-engineering.it\/fr\/wp-json\/wp\/v2\/types\/approfondimento"}],"author":[{"embeddable":true,"href":"https:\/\/www.gt-engineering.it\/fr\/wp-json\/wp\/v2\/users\/182"}],"version-history":[{"count":4,"href":"https:\/\/www.gt-engineering.it\/fr\/wp-json\/wp\/v2\/approfondimento\/37691\/revisions"}],"predecessor-version":[{"id":40620,"href":"https:\/\/www.gt-engineering.it\/fr\/wp-json\/wp\/v2\/approfondimento\/37691\/revisions\/40620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gt-engineering.it\/fr\/wp-json\/wp\/v2\/media\/37692"}],"wp:attachment":[{"href":"https:\/\/www.gt-engineering.it\/fr\/wp-json\/wp\/v2\/media?parent=37691"}],"wp:term":[{"taxonomy":"tipologia_approfondimento","embeddable":true,"href":"https:\/\/www.gt-engineering.it\/fr\/wp-json\/wp\/v2\/tipologia_approfondimento?post=37691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}